{"id":2661,"date":"2021-11-02T13:03:06","date_gmt":"2021-11-02T13:03:06","guid":{"rendered":"https:\/\/intelsynet.com\/?p=2661"},"modified":"2021-11-02T13:05:59","modified_gmt":"2021-11-02T13:05:59","slug":"estamos-seguros-en-la-nueva-era-de-la-atencion-medica-y-la-salud-digital","status":"publish","type":"post","link":"https:\/\/intelsynet.com\/es\/estamos-seguros-en-la-nueva-era-de-la-atencion-medica-y-la-salud-digital\/","title":{"rendered":"\u00bfEstamos seguros en la nueva era de la atenci\u00f3n m\u00e9dica y la salud digital?"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: left top;background-repeat: no-repeat;padding-top:4%;padding-right:0px;padding-bottom:6%;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:rgba(97,158,133,0);border-style:solid;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-animated\" style=\"margin-top:60px;margin-bottom:50px;\" data-animationType=\"fadeInDown\" data-animationDuration=\"1.0\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p>Si tenemos que elegir un\u00a0 sector que haya\u00a0 sufrido en especial\u00a0 grandes cambios, seguro que muchos de nosotros elegir\u00edamos al sector sanitario. \u00a0Su momento de enorme demanda, cargas de trabajo\u00a0 nunca vistas \u00a0y su obligada resiliencia as\u00ed lo ponen de manifiesto. Como sector esencial en cualquier sociedad, su necesidad de afrontar los continuos retos de seguridad buscando la excelencia\u00a0 es una obligaci\u00f3n en la que \u201cno se pueden poner de perfil\u201d.<\/p>\n<p>Ya antes de la pandemia, se esperaba que el mercado del sector salud digital europeo alcanzara un valor de 145. 000 millones de euros en el a\u00f1o 2025, por lo tanto estamos quiz\u00e1s, ante el mayor\u00a0 periodo de crecimiento transformador\u00a0 en el que\u00a0 se ha visto inmerso en los \u00faltimos 15 a\u00f1os.<\/p>\n<p>Forbes pronostic\u00f3 hace unos meses que la cantidad de datos dentro del sector se doblar\u00e1 cada 73 d\u00edas anualmente. A este aumento de generaci\u00f3n de datos tambi\u00e9n contribuir\u00e1 la actual crisis sanitaria, con una cifra cercana a los 3 millones de casos notificados solo en la UE hasta ahora.<\/p>\n<p>Este aumento de demanda de la atenci\u00f3n , \u00a0de los \u00a0datos que se manejan, del uso de las comunicaciones externas y\u00a0 el del \u00a0IOT en el \u00e1mbito sanitario obliga a responder \u00a0de forma contundente a la necesidad de garantizar que el entorno \u00a0sanitario posea la infraestructura de seguridad necesaria para abordar este crecimiento.<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:60px;margin-bottom:20px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"border-color:#e0e0e0;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"imageframe-align-center\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-zoomin\"><img decoding=\"async\" width=\"1076\" height=\"453\" alt=\"salud digital\" title=\"salud digital\" src=\"https:\/\/intelsynet.com\/wp-content\/uploads\/2021\/11\/1.png\" class=\"img-responsive wp-image-2662\" srcset=\"https:\/\/intelsynet.com\/wp-content\/uploads\/2021\/11\/1-200x84.png 200w, https:\/\/intelsynet.com\/wp-content\/uploads\/2021\/11\/1-400x168.png 400w, https:\/\/intelsynet.com\/wp-content\/uploads\/2021\/11\/1-600x253.png 600w, https:\/\/intelsynet.com\/wp-content\/uploads\/2021\/11\/1-800x337.png 800w, https:\/\/intelsynet.com\/wp-content\/uploads\/2021\/11\/1.png 1076w\" sizes=\"(max-width: 800px) 100vw, 1076px\" \/><\/span><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:60px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"border-color:#e0e0e0;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-2\"><p>Con la pandemia, la salud digital ha tenido una proliferaci\u00f3n de las consultas virtuales\u00a0 y atender a los pacientes a distancia, \u00a0est\u00e1 empujando al sector a cambiar su forma de trabajar, siendo a\u00fan m\u00e1s dependiente, casi de una forma cr\u00edtica,\u00a0 de dos aspectos\u00a0 importantes y viejos conocidos para el sector:<\/p>\n<ul>\n<li>La energ\u00eda<\/li>\n<li>La infraestructura digital.<\/li>\n<\/ul>\n<p>En el caso de la conectividad e IOT, el aumento sigue una carrera a altas velocidades, en 2025 se esperan m\u00e1s de 10 millones de dispositivos conectados\u00a0 en el entorno sanitario europeo, eso supone multiplicar por 5\u00a0 la cifra que ten\u00edamos en 2019.<\/p>\n<p><strong><em>La <a href=\"https:\/\/intelsynet.com\/espana-cuarta-potencia-internacional-en-ciberseguridad\/\">Ciberseguridad<\/a> tiene que venir por defecto.<\/em><\/strong><\/p>\n<p>Es obvio que\u00a0 todos los factores y aspectos de los que he hablado, aumentan exponencialmente\u00a0 la superficie de ataque actual del sector en lo que a ciberseguridad se refiere. Las puertas\u00a0 de acceso para los ciberdelincuentes se han \u00a0multiplicado \u00a0de forma significativa.\u00a0 Es verdad que antes de la pandemia la ciberseguridad ya era un gran \u00e1rea de preocupaci\u00f3n, pero, la exigencia actual generada por la innovaci\u00f3n tecnol\u00f3gica asociada a la inteligencia artificial y\u00a0 modelado 3D en el diagn\u00f3stico, \u00a0la sonorizaci\u00f3n\u00a0 a gran escala, la protecci\u00f3n de datos, software existente y el asociado a equipamiento de \u00faltima generaci\u00f3n\u2026..est\u00e1n poniendo a prueba las capacidades de seguridad f\u00edsica y l\u00f3gica que\u00a0 este sector debe tener.<\/p>\n<p>La seguridad por defecto\u00a0 en toda la infraestructura de hardware y software\u00a0 y en general a todo el equipamiento m\u00e9dico susceptible de convertirse en una puerta de acceso al entorno, debe ser una prioridad para la\u00a0 industria que abastece a todo el entorno sanitario. Sin duda alguna,\u00a0 la red de \u00a0partners tecnol\u00f3gicos especializados se enfrentan a una gran oportunidad pero tambi\u00e9n tienen una gran responsabilidad\u00a0 que no pueden eludir. Concienciar al sector y al usuario es clave para evitar grandes incidentes y ataques que doy por seguro que se van a\u00a0 generar por los ciberdelincuentes, la pregunta es \u00bfCU\u00c1NDO?, por lo tanto hay que estar preparados y trabajar hacia la minimizaci\u00f3n del riesgo\u00a0 y la obtenci\u00f3n de grandes capacidades de resiliencia.<\/p>\n<p>La monitorizaci\u00f3n y la gesti\u00f3n de incidencias- incidentes- eventos 24\/7\/365, auditorias y evaluaciones de riesgos continuas\u00a0 para toda la infraestructura de red\u00a0 y de IOT (digital ) as\u00ed como en\u00a0 los dispositivos y equipamientos m\u00e9dicos de un entorno sanitario para la salud digital se hacen\u00a0 imprescindibles\u00a0 y de obligado cumplimiento en las pol\u00edticas de gesti\u00f3n\u00a0 de este sector.<\/p>\n<h6 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"7\" data-lineheight=\"13.2px\">Carlos Aguayo<br \/>\nCEO Intelsynet<\/h6>\n<h6><\/h6>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-align-block\"><style>.fusion-button.button-1 .fusion-button-text{color:#333333;text-transform:none;}.fusion-button.button-1 i{color:#333333;}.fusion-button.button-1{border-color:#2b2b2b;border-radius:2px 2px 2px 2px;background:rgba(144,201,232,0);background-image:linear-gradient(180deg,rgba(144,201,232,0) 0%,rgba(90,171,214,0) 100%);}.fusion-button.button-1:hover .fusion-button-text,.fusion-button.button-1:hover i,.fusion-button.button-1:focus .fusion-button-text,.fusion-button.button-1:focus i,.fusion-button.button-1:active .fusion-button-text,.fusion-button.button-1:active i{color:#03a9f4;}.fusion-button.button-1:hover,.fusion-button.button-1:active,.fusion-button.button-1:focus{border-color:#03a9f4;background:rgba(90,171,214,0);background-image:linear-gradient(180deg,rgba(90,171,214,0) 0%,rgba(144,201,232,0) 100%);}<\/style><a class=\"fusion-button button-flat fusion-button-default-size button-custom button-1 fusion-button-span-yes fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/intelsynet.com\/wp-content\/uploads\/2021\/11\/\u00bfEstamos-seguros-en-la-nueva-era-de-la-atencion-medica.pdf\"><span class=\"fusion-button-text\">Descargar art\u00edculo en PDF<\/span><\/a><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-articulos"],"_links":{"self":[{"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/posts\/2661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/comments?post=2661"}],"version-history":[{"count":4,"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/posts\/2661\/revisions"}],"predecessor-version":[{"id":2668,"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/posts\/2661\/revisions\/2668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/media\/2665"}],"wp:attachment":[{"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/media?parent=2661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/categories?post=2661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intelsynet.com\/es\/wp-json\/wp\/v2\/tags?post=2661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}